﻿{"id":1516,"date":"2023-08-08T10:21:23","date_gmt":"2023-08-08T09:21:23","guid":{"rendered":"https:\/\/amblisbona.esteri.it\/?p=1516"},"modified":"2023-08-08T10:21:23","modified_gmt":"2023-08-08T09:21:23","slug":"commemorazione-del-67-anniversario-della-tragedia-di-marcinelle","status":"publish","type":"post","link":"https:\/\/amblisbona.esteri.it\/it\/news\/dall_ambasciata\/2023\/08\/commemorazione-del-67-anniversario-della-tragedia-di-marcinelle\/","title":{"rendered":"Commemorazione del 67\u00b0 anniversario della tragedia di Marcinelle"},"content":{"rendered":"<p>L\u20198 agosto viene ricordata la \u201cGiornata del Sacrificio e del Lavoro Italiano nel Mondo\u201d. Tale commemorazione \u00e8 stata istituita per valorizzare e riconoscere il lavoro e il sacrificio dei tanti connazionali emigrati all\u2019estero.<br \/>\nIl giorno prescelto fa riferimento alla tragedia mineraria di Marcinelle avvenuta nel 1956 in Belgio, dove 262 minatori persero la vita, tra cui 136 italiani.<\/p>\n<p>Quest\u2019anno, il Vice Presidente del Consiglio e Ministro degli Affari Esteri e della Cooperazione Internazionale partecipa alla cerimonia di commemorazione a Marcinelle. Per rimarcare l\u2019importanza di questa giornata, invia il seguente messaggio rivolto a tutti i connazionali all\u2019estero:<\/p>\n<p>&nbsp;<\/p>\n<p><em>Care Italiane e cari Italiani all\u2019estero,<\/em><br \/>\n<em>\u00e8 con grande emozione che oggi commemoriamo la tragedia di Marcinelle, <\/em><br \/>\n<em>nel suo 67esimo anniversario. <\/em><br \/>\n<em>In ricordo delle 262 vittime di 11 nazionalit\u00e0 diverse \u2013 e di cui 136 erano <\/em><br \/>\n<em>nostri connazionali \u2013 che persero la vita nell\u2019incidente minerario. <\/em><br \/>\n<em>\u00c8 dal 2001 che l\u20198 agosto, nella data dell\u2019anniversario di Marcinelle, si<\/em><br \/>\n<em>celebra anche la \u201cGiornata nazionale del sacrificio del lavoro italiano nel <\/em><br \/>\n<em>mondo\u201d.<\/em><br \/>\n<em>In questo spirito, ho voluto essere personalmente qui a Marcinelle, a nome <\/em><br \/>\n<em>del Governo, per portare omaggio ai milioni di italiani che vivono fuori dai <\/em><br \/>\n<em>confini nazionali e, in particolare, ai connazionali caduti sul lavoro, mentre <\/em><br \/>\n<em>contribuivano alla crescita economica, sociale e culturale dell\u2019Italia e dei Paesi<\/em><br \/>\n<em>che li avevano accolti.<\/em><br \/>\n<em>Questa triste ricorrenza mi tocca personalmente nel profondo: ho passato <\/em><br \/>\n<em>parte della mia infanzia all\u2019estero ed ho trascorso diversi anni della mia carriera <\/em><br \/>\n<em>politica nelle Istituzioni europee. Pi\u00f9 volte, negli anni scorsi, anche nella mia <\/em><br \/>\n<em>veste di Presidente del Parlamento Europeo, mi sono recato a Marcinelle. <\/em><br \/>\n<em>Il Bois du Cazier \u00e8 il luogo simbolo delle sofferenze e della fatica dei nostri <\/em><br \/>\n<em>connazionali. Il sacrificio di quei minatori ha contribuito a rafforzare la<\/em><br \/>\n<em>consapevolezza dell\u2019importanza di assicurare adeguate garanzie e sicurezza sul <\/em><br \/>\n<em>lavoro. <\/em><br \/>\n<em>Una data che il Governo italiano vuole sottolineare quest\u2019anno in modo <\/em><br \/>\n<em>solenne. Abbiamo voluto rendere speciale la commemorazione di oggi con <\/em><br \/>\n<em>l\u2019omaggio del sorvolo nei cieli di Marcinelle di due Tornado dell\u2019Aeronautica <\/em><br \/>\n<em>Militare italiana, di cui ricorre il centenario.<\/em><br \/>\n<em>Un modo per essere pi\u00f9 vicini alle nostre comunit\u00e0, una testimonianza di <\/em><br \/>\n<em>forte amicizia delle nostre Forze Armate che ogni giorno riempiono tutti gli <\/em><br \/>\n<em>italiani di orgoglio, lavorando per la sicurezza di tutti noi, in Italia e nei teatri <\/em><br \/>\n<em>internazionali.<\/em><br \/>\n<em>Il Belgio \u00e8 un Paese in cui c\u2019\u00e8 stata una forte emigrazione italiana, fin dagli <\/em><br \/>\n<em>anni 20 del secolo scorso e in particolare a partire dal secondo dopoguerra, e <\/em><br \/>\n<em>che ancora oggi accoglie molti italiani presenti nel mondo accademico, nel <\/em><br \/>\n<em>settore dei servizi cos\u00ec come in quello delle imprese e della ricerca scientifica. <\/em><br \/>\n<em>La tragedia di Marcinelle ha avuto un ruolo cruciale nel gettare le<\/em><br \/>\n<em>fondamenta dell\u2019Europa di oggi e della cittadinanza europea, ispirata ai valori <\/em><br \/>\n<em>condivisi del rispetto per la dignit\u00e0 umana, dell\u2019uguaglianza, della democrazia e <\/em><br \/>\n<em>della libera circolazione dei lavoratori. <\/em><br \/>\n<em>Valori che oggi, pi\u00f9 che mai, sono indispensabili per affrontare insieme le <\/em><br \/>\n<em>sfide globali e assicurare pace, stabilit\u00e0, sicurezza, crescita economica, <\/em><br \/>\n<em>prospettive per i giovani.<\/em><br \/>\n<em>La commemorazione di Marcinelle \u00e8 innanzitutto per tutti noi il dovere <\/em><br \/>\n<em>della memoria. Un dovere che onoriamo con convinzione ogni anno, anche per <\/em><br \/>\n<em>rendere omaggio al contributo di tutti gli italiani che sono emigrati all\u2019estero per <\/em><br \/>\n<em>ragioni di studio o di lavoro e degli italo-discendenti, che con l\u2019iniziativa del <\/em><br \/>\n<em>\u201cTurismo delle Radici\u201d, parte qualificante del nostro PNRR, vogliamo riavvicinare <\/em><br \/>\n<em>all\u2019Italia.<\/em><br \/>\n<em>A tutti i connazionali all\u2019estero, in questa importante giornata, rinnovo il <\/em><br \/>\n<em>mio pi\u00f9 sincero ringraziamento, per la passione e l\u2019impegno con cui, <\/em><br \/>\n<em>quotidianamente, continuate a rendere l\u2019Italia sempre pi\u00f9 protagonista nel<\/em><br \/>\n<em>mondo.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"L\u20198 agosto viene ricordata la \u201cGiornata del Sacrificio e del Lavoro Italiano nel Mondo\u201d. Tale commemorazione \u00e8 stata istituita per valorizzare e riconoscere il lavoro e il sacrificio dei tanti connazionali emigrati all\u2019estero. Il giorno prescelto fa riferimento alla tragedia mineraria di Marcinelle avvenuta nel 1956 in Belgio, dove 262 minatori persero la vita, tra [&hellip;]","protected":false},"author":14,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-1516","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=1516"}],"version-history":[{"count":0,"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/posts\/1516\/revisions"}],"wp:attachment":[{"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=1516"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=1516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}