﻿{"id":907,"date":"2022-07-22T17:44:29","date_gmt":"2022-07-22T16:44:29","guid":{"rendered":"https:\/\/amblisbona.esteri.it\/news\/dall_ambasciata\/2022\/07\/indizione-anticipata-delle-elezioni\/"},"modified":"2022-07-22T17:44:29","modified_gmt":"2022-07-22T16:44:29","slug":"indizione-anticipata-delle-elezioni","status":"publish","type":"post","link":"https:\/\/amblisbona.esteri.it\/it\/news\/dall_ambasciata\/2022\/07\/indizione-anticipata-delle-elezioni\/","title":{"rendered":"INDIZIONE ANTICIPATA DELLE ELEZIONI POLITICHE AL 25 SETTEMBRE 2022"},"content":{"rendered":"<p>Nella serata di ieri, 21 luglio 2022, Il Signor Presidente della Repubblica ha provveduto a sciogliere le Camere e a firmare il decreto di indizione delle elezioni politiche per il 25 settembre 2022. I decreti di scioglimento delle Camere e di convocazione dei comizi elettorali sono stati pubblicati nella Gazzetta Ufficiale n. 169 di ieri.<\/p>\n<p><strong>Opzione per il voto in Italia degli iscritti AIRE ex art. 4 legge 459\/01 \u2013 Termine: 31.07.2022<\/strong><\/p>\n<p>Ai sensi dell&#8217;art. 4 della predetta Legge, gli elettori residenti in Portogallo e iscritti all&#8217;AIRE possono esercitare l&#8217;opzione per il voto in Italia dandone comunicazione scritta a questa Rappresentanza diplomatico-consolare. La norma stabilisce che l&#8217;elettore pu\u00f2 esercitare l&#8217;opzione entro il decimo giorno successivo all\u2019indizione delle votazioni, ovvero <strong>ENTRO IL 31\/07\/2022.<\/strong><\/p>\n<p><strong>Le richieste dovranno essere indirizzate esclusivamente a questa Ambasciata e NON ai Consolati onorari.<br \/>Per l&#8217;invio si prega di utilizzare la seguente email<\/strong>: <a href=\"mailto:lisbona.elettorale@esteri.it\">lisbona.elettorale@esteri.it<\/a><\/p>\n<p>Sono qui disponibili il <a href=\"resource\/doc\/2022\/07\/comunicato_stampa_opzione_di_voto_in_italia2.docx\">comunicato stampa<\/a> per l\u2019opzione di voto in Italia e il <a href=\"resource\/doc\/2022\/07\/modulo_opzione_elezioni_politiche_2022.docx\">modulo di opzione<\/a>.<\/p>\n<p>Si acclude altresi&#8217; una <a href=\"resource\/doc\/2022\/07\/istruzioni_elezioni_politiche_2022.pdf\"><strong>guida pratica per l&#8217;elettore<\/strong><\/a> con le principali scadenze del calendario elettorale<\/p>\n<p>\u00a0<\/p>\n<p><a href=\"it\/ambasciata\/news\/dall_ambasciata\/2022\/08\/elezioni-politiche-2022-elettori.html\"><strong>OPZIONE DI VOTO PER GLI ELETTORI TEMPORANEAMENTE ALL&#8217;ESTERO<\/strong><\/a><\/p>\n<p>\u00a0<\/p>\n<p><a href=\"it\/ambasciata\/news\/dall_ambasciata\/2022\/08\/elezioni-politiche-2022-presentazione.html\">PRESENTAZIONE E AMMISSIONE CANDIDATURE CIRCOSCRIZIONE ESTERO<\/a><\/p>\n<p>\u00a0<\/p>\n<p><a href=\"it\/ambasciata\/news\/dall_ambasciata\/2022\/08\/elezioni-politiche-2022-reati-elettorali.html\"><strong>REATI ELETTORALI<\/strong><\/a><\/p>\n<p>\u00a0<\/p>\n<p><strong><span style=\"text-decoration: underline;\">SPEDIZIONE DELLE SCHEDE ELETTORALI E RILASCIO DEI DUPLICATI<\/span><\/strong><\/p>\n<p>\u00c8 in corso la spedizione delle schede elettorali.<\/p>\n<p>A partire da domenica 11 settembre, l\u2019elettore che non abbia ricevuto il plico elettorale potr\u00e0 richiedere un duplicato a questa Ambasciata secondo le modalit\u00e0 stabilite.<\/p>\n<p>Si riportano di seguito l\u2019apposito <a href=\"resource\/doc\/2022\/09\/elezioni_politiche_2022_-_comunicato_duplicati.docx\">comunicato<\/a> e un <a href=\"resource\/doc\/2022\/09\/modello_duplicati.docx\">modello<\/a> non vincolante.<\/p>\n<p>A seguito della modifica dell&#8217;art. 12, comma 5, L. 459\/2001 a opera della L. 52\/2015, NON \u00e8 pi\u00f9 richiesto che<strong> l&#8217;interessato<\/strong> si presenti PERSONALMENTE presso l&#8217;Ufficio consolare per il rilascio di un duplicato. \u00c8 quindi possibile accettare la RICHIESTA di duplicato pervenuta per mail o PEC, accompagnata da fotocopia di un documento di riconoscimento (anche se emesso da Autorit\u00e0 locali, purch\u00e9 valido). La SPEDIZIONE\/CONSEGNA del duplicato all\u2019ELETTORE \u00e8 possibile fino all&#8217;ultimo momento utile per l&#8217;espressione del voto.<\/p>\n<p>Si riporta di seguito il link alla pagina <strong>&#8221;Elezioni Politiche 2022&#8221;<\/strong> del sito web istituzionale della Farnesina, dove \u00e8 altres\u00ed possibile visualizzare dei <strong>video<\/strong> relativi alle scadenze e alle informazioni generali per l&#8217;esercizio del diritto di voto, nonch\u00e9 alle modalit\u00e1 per esprimere il voto e restituire le schede elettorali all&#8217;Ambasciata e alle responsabilit\u00e1 dell&#8217;elettore nel trattamento del materiale elettorale:\u00a0<a href=\"https:\/\/www.esteri.it\/it\/sala_stampa\/archivionotizie\/approfondimenti\/2022\/08\/elezioni-politiche-2022-2\/\">https:\/\/www.esteri.it\/it\/sala_stampa\/archivionotizie\/approfondimenti\/2022\/08\/elezioni-politiche-2022-2\/<\/a>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>ELEZIONI POLITICHE 2022: APERTURE STRAORDINARIE CANCELLERIA CONSOLARE 21 e 22 SETTEMBRE 2022<\/strong><\/span><\/p>\n<p>Oltre al normale orario di apertura, si informa che la Cancelleria Consolare di questa Ambasciata sar\u00e0 aperta, <strong>esclusivamente per il rilascio dei duplicati dei plichi elettorali<\/strong>, anche nelle seguenti date:<\/p>\n<p>&#8211; <strong>mercoled\u00ec 21 settembre dalle 9:00 alle 13:00<\/strong><\/p>\n<p>&#8211; <strong>gioved\u00ec 22 settembre dalle 14:00 alle 16:00<\/strong>.<\/p>\n<p>Si ricorda che le buste preaffrancate contenenti le schede votate <strong>dovranno pervenire a questa Ambasciata tassativamente entro le ore 16:00 di gioved\u00ec 22 settembre 2022<\/strong>.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"Nella serata di ieri, 21 luglio 2022, Il Signor Presidente della Repubblica ha provveduto a sciogliere le Camere e a firmare il decreto di indizione delle elezioni politiche per il 25 settembre 2022. I decreti di scioglimento delle Camere e di convocazione dei comizi elettorali sono stati pubblicati nella Gazzetta Ufficiale n. 169 di ieri. [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-907","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/posts\/907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=907"}],"version-history":[{"count":0,"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/posts\/907\/revisions"}],"wp:attachment":[{"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=907"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}