﻿{"id":931,"date":"2022-01-25T18:44:45","date_gmt":"2022-01-25T17:44:45","guid":{"rendered":"https:\/\/amblisbona.esteri.it\/news\/dall_ambasciata\/2022\/01\/giornata-della-memoria-2022\/"},"modified":"2022-01-25T18:44:45","modified_gmt":"2022-01-25T17:44:45","slug":"giornata-della-memoria-2022","status":"publish","type":"post","link":"https:\/\/amblisbona.esteri.it\/it\/news\/dall_ambasciata\/2022\/01\/giornata-della-memoria-2022\/","title":{"rendered":"Giornata della Memoria 2022"},"content":{"rendered":"<p>LISBONA &#8211; In occasione della Giornata Internazionale della Memoria delle Vittime dell\u2019Olocausto, l\u2019Ambasciata d\u2019Italia a Lisbona organizza un incontro multidisciplinare dal titolo &#8220;Per una memoria collettiva: le comunit\u00e0 sefardite in Italia tra la diaspora e la Shoah&#8221;, in collaborazione con la Cattedra di Studi Sefarditi \u201cAlberto Benveniste\u201d dell\u2019Universit\u00e0 di Lisbona e con l&#8217;Istituto Italiano di Cultura.<\/p>\n<p>Con l\u2019Ambasciatore Carlo Formosa interverranno la direttrice della Cattedra dedicata a Benveniste, Maria de F\u00e1tima Reis, la ricercatrice Susana Bastos Mateus e il direttore dell\u2019Istituto italiano di Cultura Stefano Scaramuzzino; seguir\u00e0 l&#8217;intervento del Prof. Giuseppe Marcocci, docente di Storia Iberica presso l&#8217;Universit\u00e0 di Oxford.<\/p>\n<p>Facendo luce sulla storia delle comunit\u00e0 sefardite della penisola iberica e sul loro rapporto con la storia degli ebrei in Italia, si traccer\u00e0 nel corso del dibattito la relazione fra le persecuzioni subite dagli ebrei sefarditi in et\u00e0 moderna e l\u2019antisemitismo contemporaneo.<\/p>\n<p>L&#8217;incontro terminer\u00e0 con una performance di lettura del poeta e drammaturgo Miguel Jesus, accompagnato da Juliana Capil\u00e9 e Nylon Princeso.<\/p>\n<p>L\u2019evento si svolger\u00e0 il <strong>27 gennaio alle ore 16.00<\/strong> (ora portoghese) sulla piattaforma <strong>Zoom<\/strong> e in diretta sulla pagina <strong>Facebook<\/strong> dell&#8217;Ambasciata.<\/p>\n<p>Disponibile la traduzione simultanea in Italiano e in Portoghese al seguente link: <a href=\"https:\/\/apportugal.zoom.us\/j\/84189022076\">https:\/\/apportugal.zoom.us\/j\/84189022076<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"LISBONA &#8211; In occasione della Giornata Internazionale della Memoria delle Vittime dell\u2019Olocausto, l\u2019Ambasciata d\u2019Italia a Lisbona organizza un incontro multidisciplinare dal titolo &#8220;Per una memoria collettiva: le comunit\u00e0 sefardite in Italia tra la diaspora e la Shoah&#8221;, in collaborazione con la Cattedra di Studi Sefarditi \u201cAlberto Benveniste\u201d dell\u2019Universit\u00e0 di Lisbona e con l&#8217;Istituto Italiano di [&hellip;]","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-931","post","type-post","status-publish","format-standard","hentry"],"_links":{"self":[{"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/posts\/931","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=931"}],"version-history":[{"count":0,"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/posts\/931\/revisions"}],"wp:attachment":[{"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=931"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amblisbona.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=931"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}